{"id":1120,"date":"2022-01-18T21:45:57","date_gmt":"2022-01-18T21:45:57","guid":{"rendered":"https:\/\/biopesaje.com\/?post_type=product&#038;p=1120"},"modified":"2025-02-05T15:21:44","modified_gmt":"2025-02-05T15:21:44","slug":"xtar","status":"publish","type":"product","link":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/","title":{"rendered":"Xtar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1120\" class=\"elementor elementor-1120\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1726a00e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1726a00e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5620fcc8\" data-id=\"5620fcc8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e352e9b elementor-widget elementor-widget-text-editor\" data-id=\"4e352e9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"w-full flex flex-wrap sm:flex-no-wrap\">\n<div class=\"w-full sm:w-3\/4 p-1 border-blue3\">\n<p class=\"w-full my-4 text-justify\">Balanza solo peso precisi\u00f3n alimentada por pilas AA, fabricada en ABS de alta resistencia, display LCD, plato en acero inoxidable de 18,5 x 14 cm. Cuenta con 3 unidades de peso, limites de peso, auto-apagado. Capacidad disponibles 1000g x 0.1g y 3000g x 0.5g.<\/p>\n\n<\/div>\n<\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5456e0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5456e0e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44e51f6\" data-id=\"44e51f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-501aa68 elementor-widget elementor-widget-heading\" data-id=\"501aa68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Documentaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af25957 elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"af25957\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-af25957\" data-scroll-on-click=\"no\" data-scroll-speed=\"300\" data-accordion-id=\"af25957\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n            <div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"documentos\" class=\"elementor-tab-title eael-accordion-header active-default\" tabindex=\"0\" data-tab=\"1\" aria-controls=\"elementor-tab-content-1831\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon far fa-file-pdf\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Documentos<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1831\" class=\"eael-accordion-content clearfix active-default\" data-tab=\"1\" aria-labelledby=\"documentos\"><p><img decoding=\"async\" class=\"wp-image-2526 alignnone\" src=\"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg.png\" alt=\"\" width=\"30\" height=\"37\" srcset=\"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg.png 391w, https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg-300x368.png 300w, https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg-244x300.png 244w, https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg-48x59.png 48w\" sizes=\"(max-width: 30px) 100vw, 30px\" \/><a href=\"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/Manual-Balanza-solo-peso-Xtar-laboratorio-industria.pdf\" target=\"_blank\" rel=\"noopener\">Manual Balanza Xtar<\/a><\/p><p><img decoding=\"async\" class=\"wp-image-2526 alignnone\" src=\"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg.png\" alt=\"\" width=\"30\" height=\"37\" srcset=\"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg.png 391w, https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg-300x368.png 300w, https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg-244x300.png 244w, https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/391px-PDF_file_icon.svg-48x59.png 48w\" sizes=\"(max-width: 30px) 100vw, 30px\" \/><a href=\"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/02\/Catalogo-Balanza-solo-peso-Xtar-laboratorio-industria.pdf\" target=\"_blank\" rel=\"noopener\">Catalogo Balanza Xtar<\/a><\/p><\/div>\n\t\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<section class=\"w-full flex flex-wrap sm:flex-no-wrap\">\n<div class=\"w-full sm:w-3\/4 p-1 border-blue3\">\n<p class=\"w-full my-4 text-justify\">Balanza solo peso precisi\u00f3n alimentada por pilas AA, fabricada en ABS de alta resistencia, display LCD, plato en acero inoxidable de 18,5 x 14 cm. Cuenta con 3 unidades de peso, limites de peso, auto-apagado. Capacidad disponibles 1000g x 0.1g y 3000g x 0.5g.<\/p>\n<\/div>\n<\/section>\n","protected":false},"featured_media":1122,"template":"","meta":{"_uag_custom_page_level_css":"","_joinchat":[],"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[41],"product_tag":[],"class_list":["post-1120","product","type-product","status-publish","has-post-thumbnail","product_cat-alanzas-solo-peso","thunk-woo-product-list","opn-qv-enable","top-store-woo-hover-none","top-store-single-product-tab-horizontal","top-store-shadow-","top-store-shadow-hover-","first","outofstock","taxable","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xtar - BIOPESAJE S.A.S.<\/title>\n<meta name=\"description\" content=\"Biopesaje S.A.S cuenta con la mejor selecci\u00f3n de equipos en categor\u00edas como pesaje, procesamiento y empaque de la industria alimenticia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biopesaje.com\/index.php\/product\/xtar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xtar - BIOPESAJE S.A.S.\" \/>\n<meta property=\"og:description\" content=\"Biopesaje S.A.S cuenta con la mejor selecci\u00f3n de equipos en categor\u00edas como pesaje, procesamiento y empaque de la industria alimenticia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biopesaje.com\/index.php\/product\/xtar\/\" \/>\n<meta property=\"og:site_name\" content=\"BIOPESAJE S.A.S.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-05T15:21:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/product\\\/xtar\\\/\",\"url\":\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/product\\\/xtar\\\/\",\"name\":\"Xtar - BIOPESAJE S.A.S.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biopesaje.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/product\\\/xtar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/product\\\/xtar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biopesaje.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/balanza-de-mesa-trumax-xtar11w.jpg\",\"datePublished\":\"2022-01-18T21:45:57+00:00\",\"dateModified\":\"2025-02-05T15:21:44+00:00\",\"description\":\"Biopesaje S.A.S cuenta con la mejor selecci\u00f3n de equipos en categor\u00edas como pesaje, procesamiento y empaque de la industria alimenticia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/product\\\/xtar\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/product\\\/xtar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/product\\\/xtar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biopesaje.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/balanza-de-mesa-trumax-xtar11w.jpg\",\"contentUrl\":\"https:\\\/\\\/biopesaje.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/balanza-de-mesa-trumax-xtar11w.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/product\\\/xtar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/biopesaje.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/biopesaje.com\\\/index.php\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Xtar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biopesaje.com\\\/#website\",\"url\":\"https:\\\/\\\/biopesaje.com\\\/\",\"name\":\"BIOPESAJE S.A.S.\",\"description\":\"Ingenier\u00eda de pesaje, metrolog\u00eda y laboratorio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/biopesaje.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biopesaje.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biopesaje.com\\\/#organization\",\"name\":\"BIOPESAJE S.A.S.\",\"url\":\"https:\\\/\\\/biopesaje.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/biopesaje.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"BIOPESAJE S.A.S.\"},\"image\":{\"@id\":\"https:\\\/\\\/biopesaje.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xtar - BIOPESAJE S.A.S.","description":"Biopesaje S.A.S cuenta con la mejor selecci\u00f3n de equipos en categor\u00edas como pesaje, procesamiento y empaque de la industria alimenticia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/","og_locale":"es_ES","og_type":"article","og_title":"Xtar - BIOPESAJE S.A.S.","og_description":"Biopesaje S.A.S cuenta con la mejor selecci\u00f3n de equipos en categor\u00edas como pesaje, procesamiento y empaque de la industria alimenticia.","og_url":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/","og_site_name":"BIOPESAJE S.A.S.","article_modified_time":"2025-02-05T15:21:44+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/","url":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/","name":"Xtar - BIOPESAJE S.A.S.","isPartOf":{"@id":"https:\/\/biopesaje.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/#primaryimage"},"image":{"@id":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/#primaryimage"},"thumbnailUrl":"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg","datePublished":"2022-01-18T21:45:57+00:00","dateModified":"2025-02-05T15:21:44+00:00","description":"Biopesaje S.A.S cuenta con la mejor selecci\u00f3n de equipos en categor\u00edas como pesaje, procesamiento y empaque de la industria alimenticia.","breadcrumb":{"@id":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biopesaje.com\/index.php\/product\/xtar\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/#primaryimage","url":"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg","contentUrl":"https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/biopesaje.com\/index.php\/product\/xtar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/biopesaje.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/biopesaje.com\/index.php\/tienda\/"},{"@type":"ListItem","position":3,"name":"Xtar"}]},{"@type":"WebSite","@id":"https:\/\/biopesaje.com\/#website","url":"https:\/\/biopesaje.com\/","name":"BIOPESAJE S.A.S.","description":"Ingenier\u00eda de pesaje, metrolog\u00eda y laboratorio.","publisher":{"@id":"https:\/\/biopesaje.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biopesaje.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/biopesaje.com\/#organization","name":"BIOPESAJE S.A.S.","url":"https:\/\/biopesaje.com\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/biopesaje.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"BIOPESAJE S.A.S."},"image":{"@id":"https:\/\/biopesaje.com\/#\/schema\/logo\/image\/"}}]}},"uagb_featured_image_src":{"full":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg",500,500,false],"thumbnail":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w-150x150.jpg",150,150,true],"medium":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w-300x300.jpg",300,300,true],"medium_large":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg",500,500,false],"large":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg",500,500,false],"1536x1536":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg",500,500,false],"2048x2048":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg",500,500,false],"woocommerce_thumbnail":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w-320x320.jpg",320,320,true],"woocommerce_single":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w.jpg",500,500,false],"woocommerce_gallery_thumbnail":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w-100x100.jpg",100,100,true],"thaps-thumb-img":["https:\/\/biopesaje.com\/wp-content\/uploads\/2022\/01\/balanza-de-mesa-trumax-xtar11w-48x48.jpg",48,48,true]},"uagb_author_info":{"display_name":"Diego Martinez","author_link":"https:\/\/biopesaje.com\/index.php\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Balanza solo peso precisi\u00f3n alimentada por pilas AA, fabricada en ABS de alta resistencia, display LCD, plato en acero inoxidable de 18,5 x 14 cm. Cuenta con 3 unidades de peso, limites de peso, auto-apagado. Capacidad disponibles 1000g x 0.1g y 3000g x 0.5g.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/product\/1120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":7,"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/product\/1120\/revisions"}],"predecessor-version":[{"id":6567,"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/product\/1120\/revisions\/6567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/media\/1122"}],"wp:attachment":[{"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/media?parent=1120"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=1120"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1120"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/biopesaje.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}